{"id":90,"date":"2022-01-21T17:18:18","date_gmt":"2022-01-21T17:18:18","guid":{"rendered":"http:\/\/www.stebhome.it\/condomini\/?page_id=90"},"modified":"2022-01-21T17:18:18","modified_gmt":"2022-01-21T17:18:18","slug":"prezzi-2","status":"publish","type":"page","link":"http:\/\/www.stebhome.it\/condomini\/prezzi-2\/","title":{"rendered":"Prezzi"},"content":{"rendered":"\n<p>Vuoi conoscere i prezzi per ottenere il sistema? Scrivici e ti invieremo le voci di capitolato comprensive di prezzi.<\/p>\n\n\n<div class=\"wpforms-container wpforms-container-full\" id=\"wpforms-53\"><form id=\"wpforms-form-53\" class=\"wpforms-validate wpforms-form\" data-formid=\"53\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/condomini\/wp-json\/wp\/v2\/pages\/90\" data-token=\"a738865feb0d6574b4455c1cf03e776d\"><noscript class=\"wpforms-error-noscript\">Abilita JavaScript nel browser per completare questo modulo.<\/noscript><div class=\"wpforms-field-container\"><div id=\"wpforms-53-field_0-container\" class=\"wpforms-field wpforms-field-name\" data-field-id=\"0\"><label class=\"wpforms-field-label\" for=\"wpforms-53-field_0\">Nome <span class=\"wpforms-required-label\">*<\/span><\/label><div class=\"wpforms-field-row wpforms-field-large\"><div class=\"wpforms-field-row-block wpforms-first wpforms-one-half\"><input type=\"text\" id=\"wpforms-53-field_0\" class=\"wpforms-field-name-first wpforms-field-required\" name=\"wpforms[fields][0][first]\" required><label for=\"wpforms-53-field_0\" class=\"wpforms-field-sublabel after \">Nome<\/label><\/div><div class=\"wpforms-field-row-block wpforms-one-half\"><input type=\"text\" id=\"wpforms-53-field_0-last\" class=\"wpforms-field-name-last wpforms-field-required\" name=\"wpforms[fields][0][last]\" required><label for=\"wpforms-53-field_0-last\" class=\"wpforms-field-sublabel after \">Cognome<\/label><\/div><\/div><\/div><div id=\"wpforms-53-field_1-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"1\"><label class=\"wpforms-field-label\" for=\"wpforms-53-field_1\">Email <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"email\" id=\"wpforms-53-field_1\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][1]\" required><\/div><div id=\"wpforms-53-field_2-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"2\"><label class=\"wpforms-field-label\" for=\"wpforms-53-field_2\">Messaggio <span class=\"wpforms-required-label\">*<\/span><\/label><textarea id=\"wpforms-53-field_2\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][2]\" required><\/textarea><\/div><\/div><div class=\"wpforms-field wpforms-field-hp\"><label for=\"wpforms-53-field-hp\" class=\"wpforms-field-label\">Name<\/label><input type=\"text\" name=\"wpforms[hp]\" id=\"wpforms-53-field-hp\" class=\"wpforms-field-medium\"><\/div><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"53\"><input type=\"hidden\" name=\"wpforms[author]\" value=\"1\"><button type=\"submit\" name=\"wpforms[submit]\" class=\"wpforms-submit button color1\" id=\"wpforms-submit-53\" value=\"wpforms-submit\" aria-live=\"assertive\" data-alt-text=\"Sending...\" data-submit-text=\"Invia\">Invia<\/button><\/div><\/form><\/div>  <!-- .wpforms-container -->","protected":false},"excerpt":{"rendered":"<p>Vuoi conoscere i prezzi per ottenere il sistema? Scrivici e ti invieremo le voci di capitolato comprensive di prezzi.<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-90","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"http:\/\/www.stebhome.it\/condomini\/wp-json\/wp\/v2\/pages\/90","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.stebhome.it\/condomini\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"http:\/\/www.stebhome.it\/condomini\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"http:\/\/www.stebhome.it\/condomini\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.stebhome.it\/condomini\/wp-json\/wp\/v2\/comments?post=90"}],"version-history":[{"count":2,"href":"http:\/\/www.stebhome.it\/condomini\/wp-json\/wp\/v2\/pages\/90\/revisions"}],"predecessor-version":[{"id":92,"href":"http:\/\/www.stebhome.it\/condomini\/wp-json\/wp\/v2\/pages\/90\/revisions\/92"}],"wp:attachment":[{"href":"http:\/\/www.stebhome.it\/condomini\/wp-json\/wp\/v2\/media?parent=90"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}